{"id":6810,"date":"2013-03-08T14:05:03","date_gmt":"2013-03-08T13:05:03","guid":{"rendered":"https:\/\/www.digitaldocument.it\/?p=6810"},"modified":"2014-07-16T14:25:07","modified_gmt":"2014-07-16T13:25:07","slug":"stampa-e-pmi-la-chiave-di-svolta-sono-gli-acquisti-intelligenti","status":"publish","type":"post","link":"https:\/\/www.digitaldocument.it\/index.php\/2013\/03\/08\/stampa-e-pmi-la-chiave-di-svolta-sono-gli-acquisti-intelligenti\/","title":{"rendered":"Stampa e Pmi, la chiave di svolta sono gli acquisti intelligenti"},"content":{"rendered":"<p>Secondo il recente White Paper di Idc <b>\u201cValutazione degli investimenti delle PMI per una stampa pi\u00f9 intelligente\u201d<\/b>, sponsorizzato da Oki Europe, le Pmi hanno la possibilit\u00e0 di tenere sotto controllo i costi e fare un uso migliore delle loro capacit\u00e0 di stampa grazie a processi di acquisto pi\u00f9 intelligenti.<\/p>\n<p>Lo studio di Idc fornisce una serie di suggerimenti relativi alle diverse fasi dell\u2019approccio al processo di acquisto, utili per tutte le PMI che intendono migliorare le proprie prestazioni di stampa:<\/p>\n<p><b>Primo step<br \/>\n<\/b>Effettuare un\u2019analisi dei sistemi di stampa Laser\/Led esistenti. L\u2019analisi dovrebbe rispondere alle seguenti domande:<\/p>\n<ul>\n<li>Quanti anni hanno le stampanti attuali? Le nuove tecnologie di stampa offrono, \u00a0infatti, prestazioni migliorate in termini di velocit\u00e0 e di qualit\u00e0 di stampa.<\/li>\n<li>Quanta energia consumano nelle diverse modalit\u00e0? Gli ultimi dispositivi consumano in media fino al 30% per cento in meno di energia e il 20% in meno di toner rispetto ai modelli precedenti.<\/li>\n<li>Quanto spazio occupano? Si pu\u00f2 ottenere un maggiore valore aggiunto in termini di versatilit\u00e0 e affidabilit\u00e0 utilizzando una stampante A3 o un multifunzione di ultima generazione, con lo stesso ingombro.<\/li>\n<li>Potrebbe essere pi\u00f9 conveniente stampare internamente a colori documenti che solitamente vengono esternalizzati? I moderni dispositivi consentono infatti l\u2019utilizzo di un\u2019ampia gamma di materiali con un\u2019elevata flessibilit\u00e0 per le basse tirature.<\/li>\n<\/ul>\n<p><b>Secondo step<br \/>\n<\/b>Sulla base della valutazione delle capacit\u00e0 di stampa attuali dell\u2019azienda, le PMI possono determinare le opzioni disponibili per un \u201cacquisto intelligente\u201d. Queste dovrebbero includere:<\/p>\n<ul>\n<li>Qualit\u00e0 e velocit\u00e0 di stampa adeguate alle esigenze dell\u2019azienda.<\/li>\n<li>Costi di esercizio del dispositivo o dei dispositivi di stampa, incluso toner, durata del tamburo e consumo energetico.<\/li>\n<li>Funzioni di risparmio energetico progettate per migliorare le prestazioni ambientali e ridurre i costi.<\/li>\n<li>Software per monitorare l\u2019utilizzo e identificare gli utenti, al fine di ripartire i costi e assegnare regole di stampa.<\/li>\n<li>Impostazioni di serie quali: stampa monocromatica, fronte\/retro e modalit\u00e0 bozza per ottimizzare l\u2019uso della carta e del toner.<\/li>\n<li>Stampa sicura con crittografia dei documenti, card con codice Pin\/Id e cancellazione automatica dei documenti non stampati.<\/li>\n<\/ul>\n<p><b>Agire subito<br \/>\n<\/b>Le nuove tecnologie di stampa permettono di essere pi\u00f9 competitivi e lo studio di Idc sottolinea come le Pmi possano ottenere il massimo dal proprio investimento nell\u2019ambito delle soluzioni di stampa.<\/p>\n<p>Il White Paper integrale, in inglese, \u00e8 disponibile per il download a <a href=\" http:\/\/www.oki.it\/IDC-white-paper\">questo indirizzo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo il recente White Paper di Idc \u201cValutazione degli investimenti delle PMI per una stampa pi\u00f9 intelligente\u201d, sponsorizzato da Oki Europe, le Pmi hanno la possibilit\u00e0 di tenere sotto controllo&hellip; <span class=\"read-more-span\"><a href=\"https:\/\/www.digitaldocument.it\/index.php\/2013\/03\/08\/stampa-e-pmi-la-chiave-di-svolta-sono-gli-acquisti-intelligenti\/\" class=\"more-link\">Continua a leggere<span class=\"screen-reader-text\"> &#8220;Stampa e Pmi, la chiave di svolta sono gli acquisti intelligenti&#8221;<\/span> <span class=\"genericon genericon-next\" aria-hidden=\"true\"><\/span><\/a><\/span><\/p>\n","protected":false},"author":9,"featured_media":6811,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[428,410,554,2141,149],"class_list":["post-6810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-printing","tag-idc","tag-oki","tag-pmi","tag-stampa-intelligente","tag-white-paper"],"jetpack_featured_media_url":"https:\/\/www.digitaldocument.it\/wp-content\/uploads\/2013\/03\/flusso-inkjet.jpg","_links":{"self":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/6810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/comments?post=6810"}],"version-history":[{"count":0,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/6810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media\/6811"}],"wp:attachment":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media?parent=6810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/categories?post=6810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/tags?post=6810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}