{"id":4871,"date":"2012-11-05T13:00:07","date_gmt":"2012-11-05T12:00:07","guid":{"rendered":"https:\/\/www.digitaldocument.it\/?p=4871"},"modified":"2014-07-16T09:28:02","modified_gmt":"2014-07-16T08:28:02","slug":"cresce-del-19-lecommerce-italiano","status":"publish","type":"post","link":"https:\/\/www.digitaldocument.it\/index.php\/2012\/11\/05\/cresce-del-19-lecommerce-italiano\/","title":{"rendered":"Cresce del 19% l\u2019eCommerce italiano"},"content":{"rendered":"<p>Sempre pi\u00f9 in alto e comunque sempre lontani dall\u2019Europa. Il successo del commercio elettronico italiano \u00e8 oggettivo, ma la crescita riduce di poco il gap con gli altri paesi europei. Scontiamo un ritardo iniziale che non si riesce a colmare anche a causa di un\u2019offerta che, pur in crescita, ha ancora ampi margini di miglioramento.<\/p>\n<p>\u201c<em>Il confronto con i principali mercati occidentali evidenzia un buono stato di salute dell\u2019eCommerce italiano, che cresce a ritmi superiori rispetto a Uk (+11% nel 2012), Francia e Germania (+12%) e Usa (+14%) anche se in valore assoluto le differenze sono importanti<\/em>&#8220;, ha commentato Riccardo Mangiaracina, responsabile della ricerca dell\u2019Osservatorio B2C Netcomm-Politecnico di Milano. &#8220;<em>Il mercato italiano \u00e8 un sesto di quello inglese (60 miliardi di euro), un quarto di quello tedesco (39 miliardi) e quasi la met\u00e0 di quello francese (2 miliardi)<\/em>.\u201d<\/p>\n<p>L\u2019Osservatorio B2c della School of Management del Politecnico di Milano rileva una crescita del 19% del valore delle vendite online, a fronte del 2% in meno dei consumi totali. L\u2019e-commerce vale 9,6 miliardi di euro con il numero dei compratori online che cresce di tre milioni di unit\u00e0 passando da 9 a 12 milioni.<\/p>\n<p><strong>Shopping sempre pi\u00f9 multicanale<\/strong><br \/>\n\u201c<em>Se il 2011 era stato l\u2019anno del boom dei siti di Couponing, dei club online e dell\u2019ingresso di Amazon, il 2012 \u00e8 invece l\u2019anno del consolidamento di questi fenomeni<\/em>&#8220;, ha commentato\u00a0Alessandro Perego, Responsabile Scientifico Osservatorio B2c\u00a0Netcomm-Politecnico di Milano. &#8220;<em>La ricerca di quest\u2019anno evidenzia inoltre il ruolo sempre pi\u00f9 rilevante della\u00a0multicanalit\u00e0, soprattutto intesa\u00a0come l\u2019utilizzo congiunto e integrato di canale fisico e canale online<\/em>.\u201d<\/p>\n<p>Molti i benefici: maggiore efficacia nel trasferimento delle informazioni grazie all\u2019Infocommerce, incremento nell\u2019efficienza dei processi di punto vendita mediante il \u201cPrenota online e ritira in negozio\u201d e miglioramento del servizio al cliente con l\u2019acquisto online e l\u2019assistenza in-store.<\/p>\n<p><strong>La crisi spinge l&#8217;online<\/strong><br \/>\n\u201c<em>Quasi 3 milioni di nuovi acquirenti online si sono affacciati su questo canale lasciando sorpresi gran parte degli operatori del settore<\/em>&#8220;, ha aggiunto Roberto Liscia, Presidente di Netcomm \u2013 Consorzio del Commercio Elettronico Italiano. &#8220;<em>Questo balzo \u00e8 da attribuire a tre ragioni principali: la crisi, che ha fatto rompere gli indugi agli internauti ancora incerti e insicuri; la forte diffusione degli smartphone, con 30 milioni di possessori, che ha reso pi\u00f9 facile l\u2019accesso a internet educando e creando il cosiddetto fenomeno \u201cme too\u201d che porta a modelli di consumo di massa; infine l\u2019evoluzione dell\u2019offerta delle vendite di abbigliamento sul modello delle Cash sales e l\u2019offerta di coupon di servizi locali fortemente scontati che hanno dato una scossa al mercato. Dal lato dell\u2019offerta oltre agli attori \u201cdiscount\u201d sono comparsi in forze i produttori del \u201cMade in Italy\u201d dalla moda e accessori al piccolo artigianato, cuore pulsante di una Italia dimenticata<\/em>.\u201d<\/p>\n<p><strong>Abbigliamento ed elettronica in testa<br \/>\n<\/strong>Per la prima volta i prodotti crescono pi\u00f9 dei servizi con l\u2019abbigliamento che, trainato dal successo di Yoox e dall\u2019arrivo di nuovi player, sale del 33%. Informatica ed elettronica di consumo crescono del 27% con una performance nettamente superiore a quella dei canali tradizionali e in crescita \u00e8 anche il grocery (+17%) anche se l\u2019offerta rimane limitata a pochi operatori.<\/p>\n<p>Fra i servizi, il turismo sale del 14% cos\u00ec come le Assicurazioni. Il turismo per\u00f2, ha ricordato Fabio Lazzerini, amministratore delegato di Amadeus Italia, vive sulla vendita di biglietti aerei e prenotazioni alberghiere, mentre \u00e8 quasi assente la vendita di pacchetti. E\u2019 un mondo dove bisogna puntare sul mobile che \u201caccelera la propensione all\u2019acquisto\u201d, come ha spiegato Vittorio Lorenzoni, country manager di Tradedoubler Italia.<\/p>\n<div>\n<div>\n<p><strong>Il ruolo centrale del Mobile<\/strong><br \/>\nL\u2019integrazione con il mobile non riguarda solo il mondo del turismo. La partita \u00e8 infatti multicanale come recita il titolo del rapporto del Politecnico di Milano. Cos\u00ec Riccardo Mangiaracina ha spiegato come un merchant su due abbia attivato un\u2019iniziativa per smartphone (App o Mobile site). \u201c99 degli oltre 200 merchant inclusi nel nostro campione hanno attivato un\u2019iniziativa per smartphone. In 37 hanno sviluppato una App, in 20 un mobile site e in 42 sia una App sia un sito mobile, muovendosi con un approccio integrato. Un terzo dei merchant con un\u2019iniziativa mobile (prevalentemente operatori multicanale) si \u00e8 orientato verso soluzioni di mobile Service (solo supporto alle fasi di pre e\/o post vendita), mentre i due terzi hanno sviluppato un\u2019iniziativa di mobile Commerce, che consente anche l\u2019ordine di un prodotto\/ servizio da Smartphone. I numeri generati dal mobile Commerce evidenziano un ruolo ancora marginale dello smartphone come canale di pura vendita, mentre assume gi\u00e0 un ruolo chiave nel supporto delle fasi di pre e post vendita\u201d.<\/p>\n<p>I casi di successo nella multicanalit\u00e0 sono ormai numerosi, ha osservato Maurizio Alberti di eCircle Italia: \u201c<em>\u00c8 possibile cambiare i comportamenti dei clienti solo grazie alle tecnologie che cambiano le abitudini<\/em>\u201d. Email marketing, recommendation e altro hanno fruttato a un retailer britannico una crescita delle vendite del canale email di oltre il 150%. Cos\u00ec come una newsletter dinamica ha fruttato una crescita del 120%. Strategie che stanno partendo anche in Italia da nomi come Marco Polo o Euronics che puntano a rilanciare i loro progetti di commercio elettronico all\u2019insegna del multicanale.<\/p>\n<p>E novit\u00e0 stanno arrivando anche sul fronte dei sistemi di pagamento. Sia ha raccontato come da marzo 2013 un altro sistema di pagamento affiancher\u00e0 quelli esistenti. Si tratta di un bonifico tramite home banking che pu\u00f2 essere utile per pagamenti oltre una certa soglia. Attraverso un pulsante sul sito dell\u2019esercente il consumatore pu\u00f2 accedere al suo home banking tramite il quale potr\u00e0 effettuare il bonifico. Le maggiori banche italiane hanno gi\u00e0 aderito al progetto che \u00e8 valido a livello europeo.<\/p>\n<p><em>fonte: Ict4Executive<\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sempre pi\u00f9 in alto e comunque sempre lontani dall\u2019Europa. Il successo del commercio elettronico italiano \u00e8 oggettivo, ma la crescita riduce di poco il gap con gli altri paesi europei.&hellip; <span class=\"read-more-span\"><a href=\"https:\/\/www.digitaldocument.it\/index.php\/2012\/11\/05\/cresce-del-19-lecommerce-italiano\/\" class=\"more-link\">Continua a leggere<span class=\"screen-reader-text\"> &#8220;Cresce del 19% l\u2019eCommerce italiano&#8221;<\/span> <span class=\"genericon genericon-next\" aria-hidden=\"true\"><\/span><\/a><\/span><\/p>\n","protected":false},"author":9,"featured_media":4872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[945,442,1992,199,1991],"class_list":["post-4871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-direct-marketing","tag-ecommerce","tag-mobile","tag-mutlicanalita","tag-ricerche-di-mercato","tag-school-of-management"],"jetpack_featured_media_url":"https:\/\/www.digitaldocument.it\/wp-content\/uploads\/2012\/11\/ecommerce.jpg","_links":{"self":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/4871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/comments?post=4871"}],"version-history":[{"count":0,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/4871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media\/4872"}],"wp:attachment":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media?parent=4871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/categories?post=4871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/tags?post=4871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}