{"id":4822,"date":"2012-11-05T11:50:03","date_gmt":"2012-11-05T10:50:03","guid":{"rendered":"https:\/\/www.digitaldocument.it\/?p=4822"},"modified":"2014-07-15T16:47:54","modified_gmt":"2014-07-15T15:47:54","slug":"e-ufficiale-drupa-continua-il-suo-ciclo-quadriennale","status":"publish","type":"post","link":"https:\/\/www.digitaldocument.it\/index.php\/2012\/11\/05\/e-ufficiale-drupa-continua-il-suo-ciclo-quadriennale\/","title":{"rendered":"E&#8217; ufficiale, drupa continua il suo ciclo quadriennale"},"content":{"rendered":"<p>Il comitato di drupa, riunitosi lo scorso 2 novembre, ha deciso che la manifestazione manterra&#039; il suo ciclo quadriennale in stile olimpico. <strong>La prossima edizione si svolger\u00e0 pertanto nel 2016, dal 31 maggio al 10 giugno<\/strong>.<\/p>\n<p>Nel prendere queste decisioni il comitato ha tenuto conto di due fattori chiave. Anzitutto un calendario internazionale di fiere e manifestazioni ormai calibrato su una drupa a cadenza quadriennale e vista come momento cardine per il mondo della stampa e della comunicazione.<\/p>\n<p>Il secondo aspetto, che ha condotto alla scelta di ridurre da due settimane a undici giorni la durata della fiera, riguarda la crescente trasformazione dell&#039;evento in un&#039;ottica b2b e la partecipazione di un sempre maggior numero di persone con incarichi di top management.<\/p>\n<p>&#8220;<em>Rispetto al 2008 questa percentuale e&#039; salita di circa il 5%, arrivando a includere circa il 78% dei visitatori internazionali<\/em>&#8220;, ha dichiarato Werner Matthias Dornscheidt, Ceo di Messe Dusseldorf. &#8220;<em>Questo rende la formula bisettimale eccessiva e siamo convinti che in undici giorni &#8211; un weekend e nove giorni lavorativi &#8211; saremo perfettamente in grado di soddisfare tanto le esigenze dei fornitori quanto quelle dei clienti<\/em>.&#8221;<\/p>\n<p>Dalla riunione e&#039; inoltre emerso il nome del chairman della prossima edizione, che sara&#039; Klaus Bolza-Schunemann, Ceo di Kba.\u00a0Bolza-Schunemann torna cosi a occupare la carica che aveva gia&#039; ricoperto nel 1995, 2000, 2004 e 2008.<\/p>\n<p>&#8220;<em>Sono entusiasta di assumere questo incarico in un momento cosi interessante. Il mercato si sta evolvendo molto in fretta e drupa 2016 sara&#039; una tappa fondamentale verso il futuro<\/em>&#8220;, ha dichiarato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il comitato di drupa, riunitosi lo scorso 2 novembre, ha deciso che la manifestazione manterra&#039; il suo ciclo quadriennale in stile olimpico. La prossima edizione si svolger\u00e0 pertanto nel 2016,&hellip; <span class=\"read-more-span\"><a href=\"https:\/\/www.digitaldocument.it\/index.php\/2012\/11\/05\/e-ufficiale-drupa-continua-il-suo-ciclo-quadriennale\/\" class=\"more-link\">Continua a leggere<span class=\"screen-reader-text\"> &#8220;E&#8217; ufficiale, drupa continua il suo ciclo quadriennale&#8221;<\/span> <span class=\"genericon genericon-next\" aria-hidden=\"true\"><\/span><\/a><\/span><\/p>\n","protected":false},"author":9,"featured_media":4828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[470,9],"tags":[1983,1982,12],"class_list":["post-4822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-box-nero","category-printing","tag-claus-bolza-schumann","tag-drupa-2016","tag-fiere"],"jetpack_featured_media_url":"https:\/\/www.digitaldocument.it\/wp-content\/uploads\/2012\/11\/mondo-drupa.jpg","_links":{"self":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/4822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/comments?post=4822"}],"version-history":[{"count":0,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/4822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media\/4828"}],"wp:attachment":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media?parent=4822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/categories?post=4822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/tags?post=4822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}