{"id":1177,"date":"2011-12-23T10:37:14","date_gmt":"2011-12-23T09:37:14","guid":{"rendered":"https:\/\/www.digitaldocument.it\/?p=1177"},"modified":"2014-07-16T11:44:33","modified_gmt":"2014-07-16T10:44:33","slug":"expo-2015-partnership-con-cisco-40-milioni-di-investimento-per-internet","status":"publish","type":"post","link":"https:\/\/www.digitaldocument.it\/index.php\/2011\/12\/23\/expo-2015-partnership-con-cisco-40-milioni-di-investimento-per-internet\/","title":{"rendered":"Expo 2015. Cisco, 40 milioni di investimento per Internet"},"content":{"rendered":"<p><a href=\"http:\/\/cisco.com\">Cisco<\/a>, con un investimento di 40 milioni di euro, collaborer\u00e0 alla realizzazione di <a href=\"http:\/\/expo2015.org\">Expo Milano 2015<\/a> a partire dal prossimo anno, progettando e costruendo le Reti Internet Protocol di nuova generazione ed una capillare infrastruttura Wi-Fi a larghissima banda. Ci\u00f2 consentir\u00e0 ai visitatori di vivere Expo 2015 in modo unico e innovativo.<\/p>\n<p>Ogni persona, infatti, avr\u00e0 la possibilit\u00e0 di personalizzare la sua visita e di avere a disposizione strumenti informativi capaci di adeguarsi agli interessi e alla personalit\u00e0 del singolo visitatore. Le soluzioni all\u2019avanguardia create per Expo Milano 2015 daranno vita a un\u2019autentica Digital Smart City e costituiranno un modello di applicazioni realizzabili in ogni area urbana.<\/p>\n<p>Cisco, multinazionale americana leader nella creazione di infrastrutture che cambiano il modo con cui le persone comunicano e collaborano, opera in Italia da circa 20 anni: \u00e8 portatrice di un bagaglio di esperienze uniche per i grandi eventi mondiali, maturato anche nella collaborazione con Expo Shanghai 2010 e le Olimpiadi di Londra 2012. Il progetto sar\u00e0 illustrato nel dettaglio in un incontro pubblico previsto per la fine del mese di gennaio.<\/p>\n<p>\u201c<em>Expo 2015 per un anno sar\u00e0 una \u201ccitt\u00e0 nella citt\u00e0\u201d che far\u00e0 di Milano un esempio sulla <\/em><em>scena mondiale delle immense potenzialit\u00e0 delle tecnologie nel costruire le comunit\u00e0 <\/em><em>del futuro, basate su forme di comunicazione e collaborazione digitali che gi\u00e0 oggi <\/em><em>sono in grado di trasformare radicalmente il modo in cui si progetta, si sviluppa, si abita <\/em><em>un ambiente urbano \u2013 ed il modo in cui i cittadini lo vivono<\/em>\u201d ha dichiarato David Bevilacqua, Amministratore Delegato di Cisco Italia. \u201c<em>La possibilit\u00e0 di essere partner di <\/em><em>Expo 2015 \u00e8 una ulteriore conferma del nostro impegno e investimento verso lo <\/em><em>sviluppo del nostro Paese, oltre che la concretizzazione della nostra visione per la <\/em><em>creazione di un nuovo e innovativo modello urbanistico, che ha come obiettivo primario <\/em><em>lo sviluppo sostenibile delle citt\u00e0, dove l&#039;essere umano e il suo benessere sono <\/em><em>prioritari e la tecnologia al servizio di una migliore qualit\u00e0 della vit<\/em>a\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cisco, con un investimento di 40 milioni di euro, collaborer\u00e0 alla realizzazione di Expo Milano 2015 a partire dal prossimo anno, progettando e costruendo le Reti Internet Protocol di nuova&hellip; <span class=\"read-more-span\"><a href=\"https:\/\/www.digitaldocument.it\/index.php\/2011\/12\/23\/expo-2015-partnership-con-cisco-40-milioni-di-investimento-per-internet\/\" class=\"more-link\">Continua a leggere<span class=\"screen-reader-text\"> &#8220;Expo 2015. Cisco, 40 milioni di investimento per Internet&#8221;<\/span> <span class=\"genericon genericon-next\" aria-hidden=\"true\"><\/span><\/a><\/span><\/p>\n","protected":false},"author":9,"featured_media":1178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[615,618,617,616],"class_list":["post-1177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-document-management","tag-cisco","tag-david-bevilacqua","tag-digital-smart-city","tag-expo-2015"],"jetpack_featured_media_url":"https:\/\/www.digitaldocument.it\/wp-content\/uploads\/2011\/12\/David-Bevilacqua.jpg","_links":{"self":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/1177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/comments?post=1177"}],"version-history":[{"count":0,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/posts\/1177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media\/1178"}],"wp:attachment":[{"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/media?parent=1177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/categories?post=1177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.digitaldocument.it\/index.php\/wp-json\/wp\/v2\/tags?post=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}